{"id":4005,"date":"2021-11-22T12:32:50","date_gmt":"2021-11-22T12:32:50","guid":{"rendered":"https:\/\/asdevices.com\/products\/gcsense\/"},"modified":"2024-04-18T18:05:50","modified_gmt":"2024-04-18T18:05:50","slug":"gcsense","status":"publish","type":"products","link":"https:\/\/asdevices.com\/fr\/produits\/gcsense\/","title":{"rendered":"GCSense"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Versatile and easy to configure, this platform is a high-quality 19-inch rackmount.<\/p>\n","protected":false},"featured_media":1072,"template":"","product-category":[102],"class_list":["post-4005","products","type-products","status-publish","has-post-thumbnail","hentry","product-category-plateformes-gc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GCSense - ASDevices<\/title>\n<meta name=\"description\" content=\"Plateforme GC en rack 19 pouces robuste et facile \u00e0 configurer, personnalisable avec diff\u00e9rents types de d\u00e9tecteurs, de vannes, etc.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/asdevices.com\/fr\/produits\/gcsense\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GCSense - ASDevices\" \/>\n<meta property=\"og:description\" content=\"Plateforme GC en rack 19 pouces robuste et facile \u00e0 configurer, personnalisable avec diff\u00e9rents types de d\u00e9tecteurs, de vannes, etc.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/asdevices.com\/fr\/produits\/gcsense\/\" \/>\n<meta property=\"og:site_name\" content=\"ASDevices\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T18:05:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/asdevices.com\/wp-content\/uploads\/2021\/11\/GCSense_KA6000_r_IMG4746-Main-Menu-Generic-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@as_devices\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/asdevices.com\\\/fr\\\/produits\\\/gcsense\\\/\",\"url\":\"https:\\\/\\\/asdevices.com\\\/fr\\\/produits\\\/gcsense\\\/\",\"name\":\"GCSense - ASDevices\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/asdevices.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/asdevices.com\\\/fr\\\/produits\\\/gcsense\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/asdevices.com\\\/fr\\\/produits\\\/gcsense\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/asdevices.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/GCSense_KA6000_r_IMG4746-Main-Menu-Generic-scaled.jpg\",\"datePublished\":\"2021-11-22T12:32:50+00:00\",\"dateModified\":\"2024-04-18T18:05:50+00:00\",\"description\":\"Plateforme GC en rack 19 pouces robuste et facile \u00e0 configurer, personnalisable avec diff\u00e9rents types de d\u00e9tecteurs, de vannes, etc.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/asdevices.com\\\/fr\\\/produits\\\/gcsense\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/asdevices.com\\\/fr\\\/produits\\\/gcsense\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asdevices.com\\\/fr\\\/produits\\\/gcsense\\\/#primaryimage\",\"url\":\"https:\\\/\\\/asdevices.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/GCSense_KA6000_r_IMG4746-Main-Menu-Generic-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/asdevices.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/GCSense_KA6000_r_IMG4746-Main-Menu-Generic-scaled.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/asdevices.com\\\/fr\\\/produits\\\/gcsense\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/asdevices.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/asdevices.com\\\/fr\\\/produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"GCSense\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/asdevices.com\\\/#website\",\"url\":\"https:\\\/\\\/asdevices.com\\\/\",\"name\":\"ASDevices\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/asdevices.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/asdevices.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/asdevices.com\\\/#organization\",\"name\":\"ASDevices\",\"url\":\"https:\\\/\\\/asdevices.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asdevices.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/cmt.a7d.mywebsitetransfer.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/asdevices_logo.png\",\"contentUrl\":\"http:\\\/\\\/cmt.a7d.mywebsitetransfer.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/asdevices_logo.png\",\"width\":370,\"height\":182,\"caption\":\"ASDevices\"},\"image\":{\"@id\":\"https:\\\/\\\/asdevices.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/as_devices\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/asdevices\\\/mycompany\\\/?viewAsMember=true\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GCSense - ASDevices","description":"Plateforme GC en rack 19 pouces robuste et facile \u00e0 configurer, personnalisable avec diff\u00e9rents types de d\u00e9tecteurs, de vannes, etc.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/asdevices.com\/fr\/produits\/gcsense\/","og_locale":"fr_FR","og_type":"article","og_title":"GCSense - ASDevices","og_description":"Plateforme GC en rack 19 pouces robuste et facile \u00e0 configurer, personnalisable avec diff\u00e9rents types de d\u00e9tecteurs, de vannes, etc.","og_url":"https:\/\/asdevices.com\/fr\/produits\/gcsense\/","og_site_name":"ASDevices","article_modified_time":"2024-04-18T18:05:50+00:00","og_image":[{"url":"https:\/\/asdevices.com\/wp-content\/uploads\/2021\/11\/GCSense_KA6000_r_IMG4746-Main-Menu-Generic-scaled.jpg","width":1,"height":1,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@as_devices","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/asdevices.com\/fr\/produits\/gcsense\/","url":"https:\/\/asdevices.com\/fr\/produits\/gcsense\/","name":"GCSense - ASDevices","isPartOf":{"@id":"https:\/\/asdevices.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/asdevices.com\/fr\/produits\/gcsense\/#primaryimage"},"image":{"@id":"https:\/\/asdevices.com\/fr\/produits\/gcsense\/#primaryimage"},"thumbnailUrl":"https:\/\/asdevices.com\/wp-content\/uploads\/2021\/11\/GCSense_KA6000_r_IMG4746-Main-Menu-Generic-scaled.jpg","datePublished":"2021-11-22T12:32:50+00:00","dateModified":"2024-04-18T18:05:50+00:00","description":"Plateforme GC en rack 19 pouces robuste et facile \u00e0 configurer, personnalisable avec diff\u00e9rents types de d\u00e9tecteurs, de vannes, etc.","breadcrumb":{"@id":"https:\/\/asdevices.com\/fr\/produits\/gcsense\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/asdevices.com\/fr\/produits\/gcsense\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asdevices.com\/fr\/produits\/gcsense\/#primaryimage","url":"https:\/\/asdevices.com\/wp-content\/uploads\/2021\/11\/GCSense_KA6000_r_IMG4746-Main-Menu-Generic-scaled.jpg","contentUrl":"https:\/\/asdevices.com\/wp-content\/uploads\/2021\/11\/GCSense_KA6000_r_IMG4746-Main-Menu-Generic-scaled.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/asdevices.com\/fr\/produits\/gcsense\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/asdevices.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/asdevices.com\/fr\/produits\/"},{"@type":"ListItem","position":3,"name":"GCSense"}]},{"@type":"WebSite","@id":"https:\/\/asdevices.com\/#website","url":"https:\/\/asdevices.com\/","name":"ASDevices","description":"","publisher":{"@id":"https:\/\/asdevices.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/asdevices.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/asdevices.com\/#organization","name":"ASDevices","url":"https:\/\/asdevices.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asdevices.com\/#\/schema\/logo\/image\/","url":"http:\/\/cmt.a7d.mywebsitetransfer.com\/wp-content\/uploads\/2021\/12\/asdevices_logo.png","contentUrl":"http:\/\/cmt.a7d.mywebsitetransfer.com\/wp-content\/uploads\/2021\/12\/asdevices_logo.png","width":370,"height":182,"caption":"ASDevices"},"image":{"@id":"https:\/\/asdevices.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/as_devices","https:\/\/www.linkedin.com\/company\/asdevices\/mycompany\/?viewAsMember=true"]}]}},"_links":{"self":[{"href":"https:\/\/asdevices.com\/fr\/wp-json\/wp\/v2\/products\/4005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asdevices.com\/fr\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/asdevices.com\/fr\/wp-json\/wp\/v2\/types\/products"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asdevices.com\/fr\/wp-json\/wp\/v2\/media\/1072"}],"wp:attachment":[{"href":"https:\/\/asdevices.com\/fr\/wp-json\/wp\/v2\/media?parent=4005"}],"wp:term":[{"taxonomy":"product-category","embeddable":true,"href":"https:\/\/asdevices.com\/fr\/wp-json\/wp\/v2\/product-category?post=4005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}